{"id":8971,"date":"2026-04-13T14:45:47","date_gmt":"2026-04-13T13:45:47","guid":{"rendered":"https:\/\/kumagumi.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1.jpg"},"modified":"2026-04-13T15:30:13","modified_gmt":"2026-04-13T14:30:13","slug":"metalslug19600_hd-1-1","status":"inherit","type":"attachment","link":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/?attachment_id=8971","title":{"rendered":"MetalSlug19600_HD-1-1"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-8971","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MetalSlug19600_HD-1-1 - KumaGumi<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MetalSlug19600_HD-1-1 - KumaGumi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"KumaGumi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuma.gumi\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T14:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MetalSlug19600_HD-1-1-scaled.jpg\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MetalSlug19600_HD-1-1-scaled.jpg\",\"name\":\"MetalSlug19600_HD-1-1 - KumaGumi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\"},\"datePublished\":\"2026-04-13T13:45:47+00:00\",\"dateModified\":\"2026-04-13T14:30:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MetalSlug19600_HD-1-1-scaled.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MetalSlug19600_HD-1-1-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MetalSlug19600_HD-1-1-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"METAL SLUG Tank T-shirt\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/product\\\/metal-slug-tank-t-shirt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MetalSlug19600_HD-1-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"name\":\"KumaGumi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\",\"name\":\"Kumagumi\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"width\":213,\"height\":143,\"caption\":\"Kumagumi\"},\"image\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kuma.gumi\",\"https:\\\/\\\/instagram.com\\\/kuma.gumi\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/kumagumifashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MetalSlug19600_HD-1-1 - KumaGumi","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"MetalSlug19600_HD-1-1 - KumaGumi","og_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg","og_site_name":"KumaGumi","article_publisher":"https:\/\/www.facebook.com\/kuma.gumi","article_modified_time":"2026-04-13T14:30:13+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg","name":"MetalSlug19600_HD-1-1 - KumaGumi","isPartOf":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website"},"datePublished":"2026-04-13T13:45:47+00:00","dateModified":"2026-04-13T14:30:13+00:00","breadcrumb":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dani027.supserv.cozmoslabs.com\/"},{"@type":"ListItem","position":2,"name":"METAL SLUG Tank T-shirt","item":"https:\/\/dani027.supserv.cozmoslabs.com\/product\/metal-slug-tank-t-shirt\/"},{"@type":"ListItem","position":3,"name":"MetalSlug19600_HD-1-1"}]},{"@type":"WebSite","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","name":"KumaGumi","description":"","publisher":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dani027.supserv.cozmoslabs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization","name":"Kumagumi","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","contentUrl":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","width":213,"height":143,"caption":"Kumagumi"},"image":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kuma.gumi","https:\/\/instagram.com\/kuma.gumi\/","https:\/\/www.pinterest.com\/kumagumifashion\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"metal_slug_hoodie-slugs-front\" srcset=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-300x300.jpg 300w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled-80x80.jpg 80w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled-450x450.jpg 450w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-1024x1024.jpg 1024w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-768x768.jpg 768w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-1536x1536.jpg 1536w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-2048x2048.jpg 2048w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-12x12.jpg 12w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-1320x1320.jpg 1320w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-50x50.jpg 50w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-100x100.jpg 100w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"metal_slug_hoodie-slugs-front","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1920,"file":"2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg","filesize":265096,"sizes":{"woocommerce_thumbnail":{"file":"MetalSlug19600_HD-1-1-scaled-300x300.jpg","width":300,"height":300,"filesize":11752,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"MetalSlug19600_HD-1-1-scaled-80x80.jpg","width":80,"height":80,"filesize":2035,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled-80x80.jpg"},"woocommerce_single":{"file":"MetalSlug19600_HD-1-1-scaled-450x450.jpg","width":450,"height":450,"filesize":21768,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled-450x450.jpg"},"medium":{"file":"MetalSlug19600_HD-1-1-300x300.jpg","width":300,"height":300,"filesize":11816,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-300x300.jpg"},"large":{"file":"MetalSlug19600_HD-1-1-1024x1024.jpg","width":1024,"height":1024,"filesize":82702,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-1024x1024.jpg"},"thumbnail":{"file":"MetalSlug19600_HD-1-1-300x300.jpg","width":300,"height":300,"filesize":11825,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-300x300.jpg"},"medium_large":{"file":"MetalSlug19600_HD-1-1-768x768.jpg","width":768,"height":768,"filesize":50290,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-768x768.jpg"},"1536x1536":{"file":"MetalSlug19600_HD-1-1-1536x1536.jpg","width":1536,"height":1536,"filesize":172539,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-1536x1536.jpg"},"2048x2048":{"file":"MetalSlug19600_HD-1-1-2048x2048.jpg","width":2048,"height":2048,"filesize":301207,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-2048x2048.jpg"},"trp-custom-language-flag":{"file":"MetalSlug19600_HD-1-1-12x12.jpg","width":12,"height":12,"filesize":768,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-12x12.jpg"},"mailpoet_newsletter_max":{"file":"MetalSlug19600_HD-1-1-1320x1320.jpg","width":1320,"height":1320,"filesize":130410,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-1320x1320.jpg"},"variation_swatches_image_size":{"file":"MetalSlug19600_HD-1-1-50x50.jpg","width":50,"height":50,"filesize":1416,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-50x50.jpg"},"variation_swatches_tooltip_size":{"file":"MetalSlug19600_HD-1-1-100x100.jpg","width":100,"height":100,"filesize":2735,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-100x100.jpg"},"full":{"file":"MetalSlug19600_HD-1-1-scaled.jpg","width":1920,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[],"alt":""}},"post":8955,"source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/04\/MetalSlug19600_HD-1-1-scaled.jpg","filename":"MetalSlug19600_HD-1-1-scaled.jpg","filesize":265096,"_links":{"self":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/media\/8971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/comments?post=8971"}],"wp:attached-to":[{"embeddable":true,"post_type":"product","id":8955,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/product\/8955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}