{"id":378,"date":"2015-05-04T18:30:10","date_gmt":"2015-05-04T18:30:10","guid":{"rendered":"https:\/\/www.kumagumi.com\/?page_id=378"},"modified":"2015-05-15T09:58:16","modified_gmt":"2015-05-15T09:58:16","slug":"terms-of-use","status":"publish","type":"page","link":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/terms-of-use\/","title":{"rendered":"Condiciones de uso"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CONDICIONES DE USO<\/strong><br \/>\nEstos t\u00e9rminos y condiciones de uso (los \u201ct\u00e9rminos\u201d) establecen los t\u00e9rminos en los que Kumagumi Inc. (\u201cKumagumi\u201d) le proporciona acceso a este sitio web (\u201cSitio\u201d). Debe leer las condiciones detenidamente antes de utilizar el sitio. Al utilizar el sitio, usted reconoce que ha le\u00eddo y que acepta cumplir las condiciones, incluida la pol\u00edtica de privacidad incorporada al presente documento por referencia. Si en cualquier momento deja de estar de acuerdo con estas condiciones, debe dejar de utilizar inmediatamente este sitio.<\/p>\n<p style=\"text-align: justify;\"><strong>AVISO LEGAL<\/strong><br \/>\nUsted reconoce expresamente que el uso que haga de este sitio es por su cuenta y riesgo. Kumagumi proporciona este sitio y su contenido \u201ctal cual, seg\u00fan est\u00e9 disponible\u201d y no ofrece garant\u00edas de ning\u00fan tipo con respecto a este sitio o su contenido. En la medida m\u00e1xima permitida por la ley, Kumagumi renuncia a todas las representaciones y garant\u00edas, incluyendo pero no limit\u00e1ndose a las garant\u00edas de comerciabilidad y adecuaci\u00f3n para un prop\u00f3sito particular - algunas jurisdicciones no permiten la exclusi\u00f3n de garant\u00edas impl\u00edcitas en determinadas circunstancias, por lo que la exclusi\u00f3n anterior puede no aplicarse en su caso. Adem\u00e1s, Kumagumi no declara ni garantiza que la informaci\u00f3n o los productos proporcionados a trav\u00e9s de este sitio sean exactos, completos o actuales.<\/p>\n<p style=\"text-align: justify;\">La informaci\u00f3n sobre productos, precios y disponibilidad est\u00e1 sujeta a cambios en cualquier momento y sin previo aviso. Los precios indicados en este Sitio no constituyen ofertas para la formalizaci\u00f3n de un contrato, sino un mero anuncio de ofertas. Salvo que se indique espec\u00edficamente en este Sitio, bajo ninguna teor\u00eda legal, extracontractual, contractual o de otro tipo, Kumagumi ni ninguno de sus directores, directivos, empleados, empresas relacionadas, filiales, comerciantes, proveedores de contenidos o cualquier otra parte implicada en la creaci\u00f3n o el mantenimiento de este sitio ser\u00e1 responsable de lo siguiente derivado o relacionado con el uso o la imposibilidad de uso de este sitio: da\u00f1os indirectos o consecuentes, p\u00e9rdida de datos, ingresos o beneficios, p\u00e9rdida o da\u00f1os a la propiedad y reclamaciones de terceros. Algunas jurisdicciones proh\u00edben la exclusi\u00f3n o limitaci\u00f3n de responsabilidad por da\u00f1os indirectos o incidentales. En consecuencia, las limitaciones y exclusiones establecidas anteriormente pueden no ser aplicables en su caso. Asimismo, Kumagumi no asume responsabilidad alguna y no ser\u00e1 responsable de los da\u00f1os o virus que puedan infectar su equipo inform\u00e1tico u otra propiedad como consecuencia de su acceso, uso o navegaci\u00f3n por el Sitio o de la descarga de cualquier material, dato, texto, imagen, v\u00eddeo o audio del Sitio.<\/p>\n<p style=\"text-align: justify;\"><strong>OFERTAS PROMOCIONALES, CONCURSOS Y SORTEOS<\/strong><br \/>\nKumagumi, Inc. se reserva el derecho a cancelar cualquier transacci\u00f3n debido al uso no autorizado, alterado, fraudulento o no elegible del descuento y a modificar o cancelar esta promoci\u00f3n debido a errores del sistema o problemas imprevistos en cualquier momento. Lea las normas oficiales que puedan acompa\u00f1ar a cada promoci\u00f3n, oferta, cup\u00f3n, descuento, concurso y\/o sorteo. Las ofertas y descuentos promocionales no se aplican a tarjetas regalo, gastos de env\u00edo o impuestos. Los descuentos aparecer\u00e1n en el momento de pagar y podr\u00e1n o no combinarse con otras ofertas o descuentos. Las ofertas especiales, cupones o descuentos no pueden utilizarse junto con otras ofertas a menos que se indique espec\u00edficamente en las normas oficiales de la oferta.<\/p>\n<p style=\"text-align: justify;\"><strong>MARCAS<\/strong><br \/>\nKumagumi es una marca registrada en Estados Unidos y otros pa\u00edses. Las marcas comerciales de Kumagumi no pueden utilizarse sin el permiso por escrito de Kumagumi y espec\u00edficamente no deben utilizarse en conexi\u00f3n con ning\u00fan otro producto o servicio, ni de ninguna manera que pueda causar confusi\u00f3n entre los clientes, ni de ninguna manera que menosprecie o desacredite a Kumagumi. Quedan reservados todos los derechos no concedidos expresamente en el presente documento.<\/p>\n<p style=\"text-align: justify;\"><strong>DERECHOS DE AUTOR Y DE PROPIEDAD<\/strong><br \/>\nToda la informaci\u00f3n, incluido, entre otros, el dise\u00f1o del Sitio, y toda la informaci\u00f3n, texto, gr\u00e1ficos, im\u00e1genes, ilustraciones, logotipos, dise\u00f1os, iconos, fotograf\u00edas, clips de v\u00eddeo y software escrito o de otro tipo, as\u00ed como todos los c\u00f3digos y scripts HTML, CGI y de otro tipo en cualquier formato utilizados para implementar el Sitio o que aparezcan en \u00e9l (\u2018Contenido\u2019) son propiedad de Kumagumi, sus proveedores de mercanc\u00edas o sus licenciantes. El dise\u00f1o general y la apariencia de este Sitio son propiedad de Kumagumi, Inc.<\/p>\n<p style=\"text-align: justify;\">El contenido de este Sitio es exclusivamente para uso personal. Se concede permiso para copiar electr\u00f3nicamente e imprimir en papel partes de este Sitio con el \u00fanico fin de realizar un pedido a Kumagumi. Usted no podr\u00e1 copiar, modificar, cargar, descargar, transmitir, (re)publicar, crear trabajos derivados, vender, revender o distribuir o explotar de cualquier otra forma ning\u00fan Contenido del Sitio, salvo en los casos expresamente permitidos por estas Condiciones. Si lo hace, violar\u00e1 los derechos de autor, marca comercial y otros derechos de propiedad de Kumagumi Inc.<\/p>\n<p style=\"text-align: justify;\">Todo el Contenido del Sitio est\u00e1 protegido por las leyes de derechos de autor, marcas comerciales y otras leyes de los Estados Unidos, as\u00ed como por los tratados y convenciones internacionales aplicables que rigen la ley de propiedad intelectual. Todas y cada una de las marcas comerciales, logotipos, encabezados de p\u00e1gina, gr\u00e1ficos personalizados, barras de botones, marcas de servicio y nombres comerciales que Kumagumi utilice en relaci\u00f3n con el Sitio seguir\u00e1n siendo propiedad exclusiva de Kumagumi. Nada de lo contenido en las Condiciones se considerar\u00e1 que le otorga ning\u00fan derecho sobre ninguna propiedad intelectual de Kumagumi. Todas las dem\u00e1s marcas comerciales, nombres de productos y nombres o logotipos de empresas que aparecen en el Sitio son propiedad de sus respectivos propietarios.<\/p>\n<p style=\"text-align: justify;\"><strong>COMUNICACIONES FACILITADAS POR EL USUARIO<\/strong><br \/>\nCualquier comunicaci\u00f3n o material que transmita al Sitio por correo electr\u00f3nico o de otro modo, incluidos datos, preguntas, comentarios, sugerencias o similares, es y ser\u00e1 tratado como no confidencial y sin derechos de propiedad. Cualquier cosa que transmita o env\u00ede podr\u00e1 ser utilizada por Kumagumi o sus filiales para cualquier fin, incluidos, entre otros, la reproducci\u00f3n, divulgaci\u00f3n, transmisi\u00f3n, publicaci\u00f3n, emisi\u00f3n y env\u00edo. Adem\u00e1s, Kumagumi es libre de utilizar cualquier idea, concepto, know-how o t\u00e9cnica contenida en cualquier comunicaci\u00f3n que usted env\u00ede al Sitio para cualquier prop\u00f3sito, incluyendo pero no limit\u00e1ndose al desarrollo, fabricaci\u00f3n y comercializaci\u00f3n de productos utilizando dicha informaci\u00f3n. Al publicar cualquier comunicaci\u00f3n o material en el sitio, usted concede a Kumagumi y a sus afiliados un derecho no exclusivo, libre de regal\u00edas, perpetuo, irrevocable y totalmente sublicenciable para utilizar, reproducir, modificar, adaptar, publicar, traducir, crear trabajos derivados, distribuir y mostrar dichas cr\u00edticas y comentarios de forma ilimitada. Tambi\u00e9n concede a Kumagumi y a sus filiales y sublicenciatarios el derecho a utilizar el nombre que env\u00ede con cualquier rese\u00f1a o comentario, si lo hubiera, en relaci\u00f3n con dicha comunicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong>COMPRAS<\/strong><br \/>\nKumagumi no garantiza, avala ni respalda ning\u00fan producto o servicio que no haya sido fabricado o prestado por Kumagumi, ni tenemos responsabilidad alguna por la calidad o el rendimiento de ning\u00fan producto o servicio que no haya sido fabricado o prestado por Kumagumi. Usted se compromete a supervisar el uso y a ser responsable de las acciones de cualquier menor que utilice su ordenador y\/o cuenta de registro para acceder a Kumagumi.<\/p>\n<p style=\"text-align: justify;\"><strong>ACEPTACI\u00d3N DEL PEDIDO<\/strong><br \/>\nLa recepci\u00f3n de una confirmaci\u00f3n de pedido por correo electr\u00f3nico no constituye la aceptaci\u00f3n de un pedido ni la confirmaci\u00f3n de una oferta de venta. Kumagumi se reserva el derecho, sin notificaci\u00f3n previa, a limitar la cantidad de pedidos de cualquier art\u00edculo y\/o a denegar el servicio a cualquier cliente. Es posible que sea necesario verificar la informaci\u00f3n antes de aceptar cualquier pedido.<\/p>\n<p style=\"text-align: justify;\"><strong>PRIVACIDAD<\/strong><br \/>\nKumagumi se compromete a cumplir todas las leyes, estatutos y reglamentos federales y estatales de Estados Unidos aplicables en relaci\u00f3n con la recopilaci\u00f3n y el uso de informaci\u00f3n personal de los visitantes del Sitio.<\/p>\n<p style=\"text-align: justify;\"><strong>INDEMNIZACI\u00d3N<\/strong><br \/>\nUsted se compromete a defender, indemnizar y mantener indemne a Kumagumi frente a cualesquiera reclamaciones, da\u00f1os, costes y gastos, incluidos los honorarios de abogados, derivados o relacionados con su uso del Sitio.<\/p>\n<p style=\"text-align: justify;\"><strong>ELECCI\u00d3N DE LA LEY<\/strong><br \/>\nLas Condiciones se regir\u00e1n e interpretar\u00e1n de conformidad con las leyes del Estado de California, Estados Unidos de Am\u00e9rica, sin tener en cuenta las disposiciones sobre conflicto de leyes. Por la presente, usted acepta la jurisdicci\u00f3n y competencia exclusivas de los tribunales federales o estatales del Condado de Orange, California, en todas las disputas que surjan o est\u00e9n relacionadas con el uso del Sitio. El uso del Sitio no est\u00e1 autorizado en ninguna jurisdicci\u00f3n que no haga efectivas todas las disposiciones de estos T\u00e9rminos, incluyendo sin limitaci\u00f3n este p\u00e1rrafo. Usted acepta que no existe ninguna relaci\u00f3n de empresa conjunta, asociaci\u00f3n, empleo o agencia entre usted y Kumagumi como resultado de este acuerdo o del uso del Sitio. Si se determina que alguna parte de este acuerdo es inv\u00e1lida o inaplicable en virtud de la legislaci\u00f3n aplicable, incluyendo, pero no limitado a, las renuncias de garant\u00eda y limitaciones de responsabilidad establecidas anteriormente, entonces la disposici\u00f3n inv\u00e1lida o inaplicable se considerar\u00e1 sustituida por una disposici\u00f3n v\u00e1lida y aplicable que m\u00e1s se acerque a la intenci\u00f3n de la disposici\u00f3n original y el resto del acuerdo continuar\u00e1 en vigor. Salvo lo especificado aqu\u00ed, este acuerdo constituye el acuerdo completo entre el usuario y Kumagumi respecto al Sitio y reemplaza a todas las comunicaciones y propuestas anteriores o contempor\u00e1neas, hayan sido \u00e9stas electr\u00f3nicas, orales o escritas, entre el usuario y Kumagumi respecto al Sitio. Una versi\u00f3n impresa de este acuerdo y de cualquier notificaci\u00f3n realizada en formato electr\u00f3nico ser\u00e1 admisible en procedimientos judiciales o administrativos basados en este acuerdo o relacionados con \u00e9l en la misma medida y con sujeci\u00f3n a las mismas condiciones que otros documentos y registros comerciales generados y conservados originalmente en formato impreso.<\/p>\n<p style=\"text-align: justify;\"><strong>TERMINACI\u00d3N<\/strong><br \/>\nKumagumi se reserva el derecho, a su entera discreci\u00f3n, de rescindir su derecho a utilizar el Sitio y cualquier derecho que se le otorgue en virtud de estas condiciones en cualquier momento, sin previo aviso, y, en consecuencia, denegarle el acceso al Sitio, si incumple cualquier t\u00e9rmino o disposici\u00f3n. Tras la rescisi\u00f3n, deber\u00e1 destruir inmediatamente todos los materiales descargados u obtenidos de otro modo de este Sitio, as\u00ed como todas las copias de dichos materiales.<\/p>","protected":false},"excerpt":{"rendered":"<p>TERMS OF USE These terms and conditions of use (the \u201cterms\u201d) set forth the terms on which Kumagumi Inc. (\u201cKumagumi\u201d) provides you access to this web site (\u201cSite\u201d). You should read the terms carefully before using the site. By using the site, you acknowledge that you have read and that you agree to abide by [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-378","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms of Use - KumaGumi<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms of Use - KumaGumi\" \/>\n<meta property=\"og:description\" content=\"TERMS OF USE These terms and conditions of use (the \u201cterms\u201d) set forth the terms on which Kumagumi Inc. (\u201cKumagumi\u201d) provides you access to this web site (\u201cSite\u201d). You should read the terms carefully before using the site. By using the site, you acknowledge that you have read and that you agree to abide by [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/es\/terms-of-use\/\" \/>\n<meta property=\"og:site_name\" content=\"KumaGumi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuma.gumi\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-15T09:58:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/terms-of-use\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/terms-of-use\\\/\",\"name\":\"Terms of Use - KumaGumi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\"},\"datePublished\":\"2015-05-04T18:30:10+00:00\",\"dateModified\":\"2015-05-15T09:58:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/terms-of-use\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/terms-of-use\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/terms-of-use\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms of Use\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"name\":\"KumaGumi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\",\"name\":\"Kumagumi\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"width\":213,\"height\":143,\"caption\":\"Kumagumi\"},\"image\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kuma.gumi\",\"https:\\\/\\\/instagram.com\\\/kuma.gumi\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/kumagumifashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condiciones de uso - KumaGumi","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Terms of Use - KumaGumi","og_description":"TERMS OF USE These terms and conditions of use (the \u201cterms\u201d) set forth the terms on which Kumagumi Inc. (\u201cKumagumi\u201d) provides you access to this web site (\u201cSite\u201d). You should read the terms carefully before using the site. By using the site, you acknowledge that you have read and that you agree to abide by [&hellip;]","og_url":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/terms-of-use\/","og_site_name":"KumaGumi","article_publisher":"https:\/\/www.facebook.com\/kuma.gumi","article_modified_time":"2015-05-15T09:58:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/terms-of-use\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/terms-of-use\/","name":"Condiciones de uso - KumaGumi","isPartOf":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website"},"datePublished":"2015-05-04T18:30:10+00:00","dateModified":"2015-05-15T09:58:16+00:00","breadcrumb":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/terms-of-use\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dani027.supserv.cozmoslabs.com\/terms-of-use\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/terms-of-use\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dani027.supserv.cozmoslabs.com\/"},{"@type":"ListItem","position":2,"name":"Terms of Use"}]},{"@type":"WebSite","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","name":"KumaGumi","description":"","publisher":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dani027.supserv.cozmoslabs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization","name":"Kumagumi","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","contentUrl":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","width":213,"height":143,"caption":"Kumagumi"},"image":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kuma.gumi","https:\/\/instagram.com\/kuma.gumi\/","https:\/\/www.pinterest.com\/kumagumifashion\/"]}]}},"_links":{"self":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/pages\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/comments?post=378"}],"version-history":[{"count":0,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/pages\/378\/revisions"}],"wp:attachment":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/es\/wp-json\/wp\/v2\/media?parent=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}