{"id":9512,"date":"2026-06-18T15:21:58","date_gmt":"2026-06-18T14:21:58","guid":{"rendered":"https:\/\/kumagumi.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg"},"modified":"2026-06-18T15:21:58","modified_gmt":"2026-06-18T14:21:58","slug":"unisex-classic-tee-white-front-6a33feff904d5-jpg","status":"inherit","type":"attachment","link":"https:\/\/dani027.supserv.cozmoslabs.com\/fr\/?attachment_id=9512","title":{"rendered":"unisex-classic-tee-white-front-6a33feff904d5.jpg"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-9512","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>unisex-classic-tee-white-front-6a33feff904d5.jpg - KumaGumi<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"unisex-classic-tee-white-front-6a33feff904d5.jpg - KumaGumi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg\" \/>\n<meta property=\"og:site_name\" content=\"KumaGumi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuma.gumi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unisex-classic-tee-white-front-6a33feff904d5.jpg\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unisex-classic-tee-white-front-6a33feff904d5.jpg\",\"name\":\"unisex-classic-tee-white-front-6a33feff904d5.jpg - KumaGumi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\"},\"datePublished\":\"2026-06-18T14:21:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unisex-classic-tee-white-front-6a33feff904d5.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unisex-classic-tee-white-front-6a33feff904d5.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/unisex-classic-tee-white-front-6a33feff904d5.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kuma Go-Chui Small\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/product\\\/kuma-go-chui-small\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"unisex-classic-tee-white-front-6a33feff904d5.jpg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"name\":\"KumaGumi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\",\"name\":\"Kumagumi\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"width\":213,\"height\":143,\"caption\":\"Kumagumi\"},\"image\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kuma.gumi\",\"https:\\\/\\\/instagram.com\\\/kuma.gumi\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/kumagumifashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"unisex-classic-tee-white-front-6a33feff904d5.jpg - KumaGumi","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"unisex-classic-tee-white-front-6a33feff904d5.jpg - KumaGumi","og_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg","og_site_name":"KumaGumi","article_publisher":"https:\/\/www.facebook.com\/kuma.gumi","og_image":[{"url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg","name":"unisex-classic-tee-white-front-6a33feff904d5.jpg - KumaGumi","isPartOf":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website"},"datePublished":"2026-06-18T14:21:58+00:00","breadcrumb":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dani027.supserv.cozmoslabs.com\/"},{"@type":"ListItem","position":2,"name":"Kuma Go-Chui Small","item":"https:\/\/dani027.supserv.cozmoslabs.com\/product\/kuma-go-chui-small\/"},{"@type":"ListItem","position":3,"name":"unisex-classic-tee-white-front-6a33feff904d5.jpg"}]},{"@type":"WebSite","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","name":"KumaGumi","description":"","publisher":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dani027.supserv.cozmoslabs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization","name":"Kumagumi","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","contentUrl":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","width":213,"height":143,"caption":"Kumagumi"},"image":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kuma.gumi","https:\/\/instagram.com\/kuma.gumi\/","https:\/\/www.pinterest.com\/kumagumifashion\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg 300w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-1024x1024.jpg 1024w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-768x768.jpg 768w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-1536x1536.jpg 1536w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-12x12.jpg 12w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-1320x1320.jpg 1320w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-450x450.jpg 450w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-80x80.jpg 80w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-50x50.jpg 50w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-100x100.jpg 100w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-scaled.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1920,"file":"2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-scaled.jpg","filesize":134796,"sizes":{"medium":{"file":"unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg","width":300,"height":300,"filesize":5037,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg"},"large":{"file":"unisex-classic-tee-white-front-6a33feff904d5-1024x1024.jpg","width":1024,"height":1024,"filesize":39934,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-1024x1024.jpg"},"thumbnail":{"file":"unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg","width":300,"height":300,"filesize":5037,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg"},"medium_large":{"file":"unisex-classic-tee-white-front-6a33feff904d5-768x768.jpg","width":768,"height":768,"filesize":23328,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-768x768.jpg"},"1536x1536":{"file":"unisex-classic-tee-white-front-6a33feff904d5-1536x1536.jpg","width":1536,"height":1536,"filesize":86684,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-1536x1536.jpg"},"trp-custom-language-flag":{"file":"unisex-classic-tee-white-front-6a33feff904d5-12x12.jpg","width":12,"height":12,"filesize":723,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-12x12.jpg"},"mailpoet_newsletter_max":{"file":"unisex-classic-tee-white-front-6a33feff904d5-1320x1320.jpg","width":1320,"height":1320,"filesize":64756,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-1320x1320.jpg"},"woocommerce_thumbnail":{"file":"unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg","width":300,"height":300,"filesize":5037,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-300x300.jpg"},"woocommerce_single":{"file":"unisex-classic-tee-white-front-6a33feff904d5-450x450.jpg","width":450,"height":450,"filesize":9471,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-450x450.jpg"},"woocommerce_gallery_thumbnail":{"file":"unisex-classic-tee-white-front-6a33feff904d5-80x80.jpg","width":80,"height":80,"filesize":1211,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-80x80.jpg"},"variation_swatches_image_size":{"file":"unisex-classic-tee-white-front-6a33feff904d5-50x50.jpg","width":50,"height":50,"filesize":973,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-50x50.jpg"},"variation_swatches_tooltip_size":{"file":"unisex-classic-tee-white-front-6a33feff904d5-100x100.jpg","width":100,"height":100,"filesize":1487,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-100x100.jpg"},"full":{"file":"unisex-classic-tee-white-front-6a33feff904d5-scaled.jpg","width":1920,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[],"alt":""},"original_image":"unisex-classic-tee-white-front-6a33feff904d5.jpg"},"post":4306,"source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2026\/06\/unisex-classic-tee-white-front-6a33feff904d5-scaled.jpg","filename":"unisex-classic-tee-white-front-6a33feff904d5.jpg","filesize":134796,"_links":{"self":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/fr\/wp-json\/wp\/v2\/media\/9512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/fr\/wp-json\/wp\/v2\/comments?post=9512"}],"wp:attached-to":[{"embeddable":true,"post_type":"product","id":4306,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/fr\/wp-json\/wp\/v2\/product\/4306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}