{"id":4442,"date":"2022-03-17T17:22:28","date_gmt":"2022-03-17T17:22:28","guid":{"rendered":"https:\/\/kumagumi.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg"},"modified":"2022-03-17T17:22:28","modified_gmt":"2022-03-17T17:22:28","slug":"differ_new-1200","status":"inherit","type":"attachment","link":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/ss-2022-tougeki\/differ_new-1200\/","title":{"rendered":"\u30c7\u30a3\u30d5\u30a1\u30ec\u30f3\u30b7\u30a2_new-1200"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-4442","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>differ_new-1200 - KumaGumi<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"differ_new-1200 - KumaGumi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg\" \/>\n<meta property=\"og:site_name\" content=\"KumaGumi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuma.gumi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/differ_new-1200.jpg\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/differ_new-1200.jpg\",\"name\":\"differ_new-1200 - KumaGumi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\"},\"datePublished\":\"2022-03-17T17:22:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/differ_new-1200.jpg#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/differ_new-1200.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/differ_new-1200.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SS 2022 : TOUGEKI\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/ss-2022-tougeki\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"differ_new-1200\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"name\":\"KumaGumi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\",\"name\":\"Kumagumi\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"width\":213,\"height\":143,\"caption\":\"Kumagumi\"},\"image\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kuma.gumi\",\"https:\\\/\\\/instagram.com\\\/kuma.gumi\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/kumagumifashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"differ_new-1200 - \u718a\u7d44","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ja_JP","og_type":"article","og_title":"differ_new-1200 - KumaGumi","og_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg","og_site_name":"KumaGumi","article_publisher":"https:\/\/www.facebook.com\/kuma.gumi","og_image":[{"width":1200,"height":800,"url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg","name":"differ_new-1200 - \u718a\u7d44","isPartOf":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website"},"datePublished":"2022-03-17T17:22:28+00:00","breadcrumb":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dani027.supserv.cozmoslabs.com\/"},{"@type":"ListItem","position":2,"name":"SS 2022 : TOUGEKI","item":"https:\/\/dani027.supserv.cozmoslabs.com\/ss-2022-tougeki\/"},{"@type":"ListItem","position":3,"name":"differ_new-1200"}]},{"@type":"WebSite","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","name":"\u718a\u7d44","description":"","publisher":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dani027.supserv.cozmoslabs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization","name":"\u718a\u7d44","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","contentUrl":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","width":213,"height":143,"caption":"Kumagumi"},"image":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kuma.gumi","https:\/\/instagram.com\/kuma.gumi\/","https:\/\/www.pinterest.com\/kumagumifashion\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-300x200.jpg 300w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-450x300.jpg 450w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-1024x683.jpg 1024w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-768x512.jpg 768w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-600x400.jpg 600w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":800,"file":"2022\/03\/differ_new-1200.jpg","filesize":171667,"sizes":{"woocommerce_thumbnail":{"file":"differ_new-1200-300x300.jpg","width":300,"height":300,"filesize":22887,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"differ_new-1200-80x80.jpg","width":80,"height":80,"filesize":3208,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-80x80.jpg"},"woocommerce_single":{"file":"differ_new-1200-450x300.jpg","width":450,"height":300,"filesize":30741,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-450x300.jpg"},"medium":{"file":"differ_new-1200-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-300x200.jpg"},"large":{"file":"differ_new-1200-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-1024x683.jpg"},"thumbnail":{"file":"differ_new-1200-200x200.jpg","width":200,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-200x200.jpg"},"medium_large":{"file":"differ_new-1200-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-768x512.jpg"},"wysija-newsletters-max":{"file":"differ_new-1200-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-600x400.jpg"},"shop_single":{"file":"differ_new-1200-450x300.jpg","width":450,"height":300,"filesize":30703,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-450x300.jpg"},"shop_thumbnail":{"file":"differ_new-1200-80x80.jpg","width":80,"height":80,"filesize":3215,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200-80x80.jpg"},"full":{"file":"differ_new-1200.jpg","width":1200,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg"}},"image_meta":{"aperture":"3.2","credit":"","camera":"Canon EOS 5DS","caption":"","created_timestamp":"946717351","copyright":"","focal_length":"47","iso":"100","shutter_speed":"0.3","title":"","orientation":"65535","keywords":[],"alt":""}},"post":4440,"source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/03\/differ_new-1200.jpg","filename":"differ_new-1200.jpg","filesize":171667,"_links":{"self":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media\/4442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/comments?post=4442"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":4440,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/pages\/4440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}