{"id":4997,"date":"2022-10-12T14:23:28","date_gmt":"2022-10-12T14:23:28","guid":{"rendered":"https:\/\/kumagumi.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg"},"modified":"2022-10-12T14:23:28","modified_gmt":"2022-10-12T14:23:28","slug":"inside-close_black","status":"inherit","type":"attachment","link":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/?attachment_id=4997","title":{"rendered":"close_black \u306e\u5185\u5074"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-4997","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>inside close_black - KumaGumi<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"inside close_black - KumaGumi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg\" \/>\n<meta property=\"og:site_name\" content=\"KumaGumi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuma.gumi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/inside-close_black.jpg\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/inside-close_black.jpg\",\"name\":\"inside close_black - KumaGumi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\"},\"datePublished\":\"2022-10-12T14:23:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/inside-close_black.jpg#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/inside-close_black.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/inside-close_black.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Famitsu T-shirt\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/product\\\/famitsu\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"inside close_black\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"name\":\"KumaGumi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\",\"name\":\"Kumagumi\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"width\":213,\"height\":143,\"caption\":\"Kumagumi\"},\"image\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kuma.gumi\",\"https:\\\/\\\/instagram.com\\\/kuma.gumi\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/kumagumifashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"inside close_black - \u304f\u307e\u7d44","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ja_JP","og_type":"article","og_title":"inside close_black - KumaGumi","og_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg","og_site_name":"KumaGumi","article_publisher":"https:\/\/www.facebook.com\/kuma.gumi","og_image":[{"width":1920,"height":1920,"url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg","name":"inside close_black - \u304f\u307e\u7d44","isPartOf":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website"},"datePublished":"2022-10-12T14:23:28+00:00","breadcrumb":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dani027.supserv.cozmoslabs.com\/"},{"@type":"ListItem","position":2,"name":"Famitsu T-shirt","item":"https:\/\/dani027.supserv.cozmoslabs.com\/product\/famitsu\/"},{"@type":"ListItem","position":3,"name":"inside close_black"}]},{"@type":"WebSite","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","name":"\u718a\u7d44","description":"","publisher":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dani027.supserv.cozmoslabs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization","name":"\u718a\u7d44","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","contentUrl":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","width":213,"height":143,"caption":"Kumagumi"},"image":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kuma.gumi","https:\/\/instagram.com\/kuma.gumi\/","https:\/\/www.pinterest.com\/kumagumifashion\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-300x300.jpg 300w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-80x80.jpg 80w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-450x450.jpg 450w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-1024x1024.jpg 1024w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-768x768.jpg 768w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-1536x1536.jpg 1536w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-2048x2048.jpg 2048w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-1320x1320.jpg 1320w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-50x50.jpg 50w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-100x100.jpg 100w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-scaled.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1920,"file":"2022\/10\/inside-close_black-scaled-scaled.jpg","filesize":966502,"sizes":{"woocommerce_thumbnail":{"file":"inside-close_black-scaled-300x300.jpg","width":300,"height":300,"filesize":30964,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"inside-close_black-scaled-80x80.jpg","width":80,"height":80,"filesize":2274,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-80x80.jpg"},"woocommerce_single":{"file":"inside-close_black-scaled-450x450.jpg","width":450,"height":450,"filesize":72619,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-450x450.jpg"},"medium":{"file":"inside-close_black-300x300.jpg","width":300,"height":300,"filesize":31265,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-300x300.jpg"},"large":{"file":"inside-close_black-1024x1024.jpg","width":1024,"height":1024,"filesize":353047,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-1024x1024.jpg"},"thumbnail":{"file":"inside-close_black-300x300.jpg","width":300,"height":300,"filesize":31246,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-300x300.jpg"},"medium_large":{"file":"inside-close_black-768x768.jpg","width":768,"height":768,"filesize":207878,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-768x768.jpg"},"1536x1536":{"file":"inside-close_black-1536x1536.jpg","width":1536,"height":1536,"filesize":711121,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-1536x1536.jpg"},"2048x2048":{"file":"inside-close_black-2048x2048.jpg","width":2048,"height":2048,"filesize":1131072,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-2048x2048.jpg"},"mailpoet_newsletter_max":{"file":"inside-close_black-1320x1320.jpg","width":1320,"height":1320,"filesize":551257,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-1320x1320.jpg"},"variation_swatches_image_size":{"file":"inside-close_black-50x50.jpg","width":50,"height":50,"filesize":1398,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-50x50.jpg"},"variation_swatches_tooltip_size":{"file":"inside-close_black-100x100.jpg","width":100,"height":100,"filesize":3278,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-100x100.jpg"},"full":{"file":"inside-close_black-scaled-scaled.jpg","width":1920,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[],"alt":""},"original_image":"inside-close_black-scaled.jpg"},"post":4978,"source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2022\/10\/inside-close_black-scaled-scaled.jpg","filename":"inside-close_black-scaled.jpg","filesize":966502,"_links":{"self":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media\/4997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/comments?post=4997"}],"wp:attached-to":[{"embeddable":true,"post_type":"product","id":4978,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/product\/4978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}