{"id":5731,"date":"2023-06-02T15:45:20","date_gmt":"2023-06-02T15:45:20","guid":{"rendered":"https:\/\/kumagumi.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg"},"modified":"2023-06-02T15:45:20","modified_gmt":"2023-06-02T15:45:20","slug":"typeb_tshirt_close","status":"inherit","type":"attachment","link":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/?attachment_id=5731","title":{"rendered":"\u30bf\u30a4\u30d7B_\u30b7\u30e3\u30c4\u30fb\u30af\u30ed\u30fc\u30ba"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-5731","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>typeB_tshirt_close - KumaGumi<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"typeB_tshirt_close - KumaGumi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg\" \/>\n<meta property=\"og:site_name\" content=\"KumaGumi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuma.gumi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/typeB_tshirt_close.jpg\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/typeB_tshirt_close.jpg\",\"name\":\"typeB_tshirt_close - KumaGumi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\"},\"datePublished\":\"2023-06-02T15:45:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/typeB_tshirt_close.jpg#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/typeB_tshirt_close.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/typeB_tshirt_close.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Type-B T-shirt\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/product\\\/type-b\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"typeB_tshirt_close\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"name\":\"KumaGumi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\",\"name\":\"Kumagumi\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"width\":213,\"height\":143,\"caption\":\"Kumagumi\"},\"image\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kuma.gumi\",\"https:\\\/\\\/instagram.com\\\/kuma.gumi\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/kumagumifashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"typeB_tshirt_close - \u718a\u7d44","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ja_JP","og_type":"article","og_title":"typeB_tshirt_close - KumaGumi","og_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg","og_site_name":"KumaGumi","article_publisher":"https:\/\/www.facebook.com\/kuma.gumi","og_image":[{"url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg","name":"typeB_tshirt_close - \u718a\u7d44","isPartOf":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website"},"datePublished":"2023-06-02T15:45:20+00:00","breadcrumb":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dani027.supserv.cozmoslabs.com\/"},{"@type":"ListItem","position":2,"name":"Type-B T-shirt","item":"https:\/\/dani027.supserv.cozmoslabs.com\/product\/type-b\/"},{"@type":"ListItem","position":3,"name":"typeB_tshirt_close"}]},{"@type":"WebSite","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","name":"\u718a\u7d44","description":"","publisher":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dani027.supserv.cozmoslabs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization","name":"\u718a\u7d44","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","contentUrl":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","width":213,"height":143,"caption":"Kumagumi"},"image":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kuma.gumi","https:\/\/instagram.com\/kuma.gumi\/","https:\/\/www.pinterest.com\/kumagumifashion\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"300\" src=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-297x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-297x300.jpg 297w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-80x80.jpg 80w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-450x454.jpg 450w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-1015x1024.jpg 1015w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-768x775.jpg 768w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-12x12.jpg 12w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-1320x1331.jpg 1320w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-50x50.jpg 50w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-100x100.jpg 100w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg 1384w\" sizes=\"auto, (max-width: 297px) 100vw, 297px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1384,"height":1396,"file":"2023\/06\/typeB_tshirt_close.jpg","filesize":249476,"sizes":{"woocommerce_thumbnail":{"file":"typeB_tshirt_close-300x300.jpg","width":300,"height":300,"filesize":14570,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"typeB_tshirt_close-80x80.jpg","width":80,"height":80,"filesize":2057,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-80x80.jpg"},"woocommerce_single":{"file":"typeB_tshirt_close-450x454.jpg","width":450,"height":454,"filesize":28817,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-450x454.jpg"},"medium":{"file":"typeB_tshirt_close-297x300.jpg","width":297,"height":300,"filesize":14702,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-297x300.jpg"},"large":{"file":"typeB_tshirt_close-1015x1024.jpg","width":1015,"height":1024,"filesize":106086,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-1015x1024.jpg"},"thumbnail":{"file":"typeB_tshirt_close-300x300.jpg","width":300,"height":300,"filesize":14570,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-300x300.jpg"},"medium_large":{"file":"typeB_tshirt_close-768x775.jpg","width":768,"height":775,"filesize":69153,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-768x775.jpg"},"trp-custom-language-flag":{"file":"typeB_tshirt_close-12x12.jpg","width":12,"height":12,"filesize":754,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-12x12.jpg"},"mailpoet_newsletter_max":{"file":"typeB_tshirt_close-1320x1331.jpg","width":1320,"height":1331,"filesize":156995,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-1320x1331.jpg"},"variation_swatches_image_size":{"file":"typeB_tshirt_close-50x50.jpg","width":50,"height":50,"filesize":1333,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-50x50.jpg"},"variation_swatches_tooltip_size":{"file":"typeB_tshirt_close-100x100.jpg","width":100,"height":100,"filesize":2724,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close-100x100.jpg"},"full":{"file":"typeB_tshirt_close.jpg","width":1384,"height":1396,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg"}},"image_meta":{"aperture":"3.2","credit":"","camera":"DC-G9","caption":"","created_timestamp":"1683542056","copyright":"","focal_length":"18","iso":"400","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[],"alt":""}},"post":5715,"source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2023\/06\/typeB_tshirt_close.jpg","filename":"typeB_tshirt_close.jpg","filesize":249476,"_links":{"self":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media\/5731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/comments?post=5731"}],"wp:attached-to":[{"embeddable":true,"post_type":"product","id":5715,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/product\/5715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}