{"id":6741,"date":"2024-02-01T14:31:05","date_gmt":"2024-02-01T14:31:05","guid":{"rendered":"https:\/\/kumagumi.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg"},"modified":"2024-02-01T14:31:16","modified_gmt":"2024-02-01T14:31:16","slug":"tekken_supreme_puffedparka-1024x576","status":"inherit","type":"attachment","link":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/is-video-game-merchandise-clothing-finally-becoming-fashionable\/tekken_supreme_puffedparka-1024x576\/","title":{"rendered":"\u9244\u62f3_\u30b7\u30e5\u30d7\u30ea\u30fc\u30e0_\u30d1\u30d5\u30c9\u30d1\u30fc\u30ab-1024\u00d7576"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-6741","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tekken_Supreme_PuffedParka-1024x576 - KumaGumi<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tekken_Supreme_PuffedParka-1024x576 - KumaGumi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"KumaGumi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuma.gumi\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-01T14:31:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Tekken_Supreme_PuffedParka-1024x576-1.jpg\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Tekken_Supreme_PuffedParka-1024x576-1.jpg\",\"name\":\"Tekken_Supreme_PuffedParka-1024x576 - KumaGumi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\"},\"datePublished\":\"2024-02-01T14:31:05+00:00\",\"dateModified\":\"2024-02-01T14:31:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Tekken_Supreme_PuffedParka-1024x576-1.jpg#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Tekken_Supreme_PuffedParka-1024x576-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Tekken_Supreme_PuffedParka-1024x576-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Is Gaming Merchandise\\\/Clothing Finally Becoming Fashionable ?\",\"item\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/is-video-game-merchandise-clothing-finally-becoming-fashionable\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tekken_Supreme_PuffedParka-1024&#215;576\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#website\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"name\":\"KumaGumi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#organization\",\"name\":\"Kumagumi\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo.png\",\"width\":213,\"height\":143,\"caption\":\"Kumagumi\"},\"image\":{\"@id\":\"https:\\\/\\\/dani027.supserv.cozmoslabs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kuma.gumi\",\"https:\\\/\\\/instagram.com\\\/kuma.gumi\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/kumagumifashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u9244\u62f3_Supreme_PuffedParka-1024x576 - KumaGumi","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ja_JP","og_type":"article","og_title":"Tekken_Supreme_PuffedParka-1024x576 - KumaGumi","og_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg","og_site_name":"KumaGumi","article_publisher":"https:\/\/www.facebook.com\/kuma.gumi","article_modified_time":"2024-02-01T14:31:16+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg","name":"\u9244\u62f3_Supreme_PuffedParka-1024x576 - KumaGumi","isPartOf":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website"},"datePublished":"2024-02-01T14:31:05+00:00","dateModified":"2024-02-01T14:31:16+00:00","breadcrumb":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dani027.supserv.cozmoslabs.com\/"},{"@type":"ListItem","position":2,"name":"Is Gaming Merchandise\/Clothing Finally Becoming Fashionable ?","item":"https:\/\/dani027.supserv.cozmoslabs.com\/is-video-game-merchandise-clothing-finally-becoming-fashionable\/"},{"@type":"ListItem","position":3,"name":"Tekken_Supreme_PuffedParka-1024&#215;576"}]},{"@type":"WebSite","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#website","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","name":"\u718a\u7d44","description":"","publisher":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dani027.supserv.cozmoslabs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#organization","name":"\u718a\u7d44","url":"https:\/\/dani027.supserv.cozmoslabs.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/","url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","contentUrl":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2015\/04\/logo.png","width":213,"height":143,"caption":"Kumagumi"},"image":{"@id":"https:\/\/dani027.supserv.cozmoslabs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kuma.gumi","https:\/\/instagram.com\/kuma.gumi\/","https:\/\/www.pinterest.com\/kumagumifashion\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"gaming merchandising\" srcset=\"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-300x169.jpg 300w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-450x253.jpg 450w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-768x432.jpg 768w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-18x10.jpg 18w, https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"gaming merchandising","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":576,"file":"2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg","filesize":67699,"sizes":{"woocommerce_thumbnail":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-300x300.jpg","width":300,"height":300,"filesize":14617,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-80x80.jpg","width":80,"height":80,"filesize":2309,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-80x80.jpg"},"woocommerce_single":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-450x253.jpg","width":450,"height":253,"filesize":15857,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-450x253.jpg"},"medium":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-300x169.jpg","width":300,"height":169,"filesize":8780,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-300x169.jpg"},"thumbnail":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-300x300.jpg","width":300,"height":300,"filesize":14617,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-300x300.jpg"},"medium_large":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-768x432.jpg","width":768,"height":432,"filesize":35789,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-768x432.jpg"},"trp-custom-language-flag":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-18x10.jpg","width":18,"height":10,"filesize":847,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-18x10.jpg"},"variation_swatches_image_size":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-50x50.jpg","width":50,"height":50,"filesize":1614,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-50x50.jpg"},"variation_swatches_tooltip_size":{"file":"Tekken_Supreme_PuffedParka-1024x576-1-100x100.jpg","width":100,"height":100,"filesize":3195,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1-100x100.jpg"},"full":{"file":"Tekken_Supreme_PuffedParka-1024x576-1.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[],"alt":""}},"post":6736,"source_url":"https:\/\/dani027.supserv.cozmoslabs.com\/wp-content\/uploads\/2024\/02\/Tekken_Supreme_PuffedParka-1024x576-1.jpg","filename":"Tekken_Supreme_PuffedParka-1024x576-1.jpg","filesize":67699,"_links":{"self":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media\/6741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/comments?post=6741"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6736,"href":"https:\/\/dani027.supserv.cozmoslabs.com\/jp\/wp-json\/wp\/v2\/posts\/6736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}